{"id":789,"date":"2026-04-20T02:15:59","date_gmt":"2026-04-20T02:15:59","guid":{"rendered":"https:\/\/preview.minasoft.vn\/?page_id=789"},"modified":"2026-04-28T15:29:38","modified_gmt":"2026-04-28T08:29:38","slug":"demo","status":"publish","type":"page","link":"https:\/\/preview.minasoft.vn\/en\/demo\/","title":{"rendered":"Live Preview"},"content":{"rendered":"<p>0888.139.578<\/p>","protected":false},"excerpt":{"rendered":"<p>0888.139.578<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":99999,"comment_status":"closed","ping_status":"closed","template":"wp-extra-demo-page.php","meta":{"footnotes":""},"class_list":["post-789","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/pages\/789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/comments?post=789"}],"version-history":[{"count":1,"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/pages\/789\/revisions"}],"predecessor-version":[{"id":3248,"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/pages\/789\/revisions\/3248"}],"wp:attachment":[{"href":"https:\/\/preview.minasoft.vn\/en\/wp-json\/wp\/v2\/media?parent=789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}